{"id":4176,"date":"2021-11-02T09:50:00","date_gmt":"2021-11-02T09:50:00","guid":{"rendered":"https:\/\/staging.wilegal.it\/?p=4176"},"modified":"2022-09-09T09:51:23","modified_gmt":"2022-09-09T09:51:23","slug":"oltre-200-aziende-al-nostro-grande-evento-agenda-2030","status":"publish","type":"post","link":"https:\/\/staging.wilegal.it\/en\/oltre-200-aziende-al-nostro-grande-evento-agenda-2030\/","title":{"rendered":"Oltre 200 aziende al nostro grande evento Agenda 2030"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Grazie alle oltre 200 aziende che gioved\u00ec 28 ottobre hanno preso parte al nostro convegno dedicato al lavoro che cambia organizzato alla Triennale di Milano. Come <strong>WI LEGAL vogliamo affiancare le aziende nei processi di miglioramento del lavoro<\/strong> perch\u00e9, come dice il nostro nome, ci siamo presi l\u2019impegno di essere \u201cwork improvers\u201d. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E\u2019 stato un grande onore cominciare l&#8217;evento con i saluti di <strong>Stefano Boeri, Presidente di Triennale Milano<\/strong> e condividere il messaggio di saluto del <strong>Ministro per la Pubblica Amministrazione On. Prof. Renato Brunetta<\/strong>. Come facciamo da tre anni, ad \u201cAgenda 2030\u201d abbiamo raccontato storie di aziende e di persone che stanno portando avanti progetti rilevanti. Un ringraziamente speciale va a tutti gli speakers che con i loro racconti e la loro esperienza ci hanno saputo ispirare, ci hanno regalato spunti nuovi, idee sulle quali riflettere e ci hanno indicato la direzione da seguire per realizzare il lavoro del futuro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Grazie alle oltre 200 aziende che gioved\u00ec 28 ottobre hanno preso parte al nostro convegno dedicato al lavoro che cambia organizzato alla Triennale di Milano. Come WI LEGAL vogliamo affiancare le aziende nei processi di miglioramento del lavoro perch\u00e9, come dice il nostro nome, ci siamo presi l\u2019impegno di essere \u201cwork improvers\u201d. E\u2019 stato un [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4075,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30],"tags":[],"class_list":["post-4176","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-events"],"_links":{"self":[{"href":"https:\/\/staging.wilegal.it\/en\/wp-json\/wp\/v2\/posts\/4176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.wilegal.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.wilegal.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.wilegal.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.wilegal.it\/en\/wp-json\/wp\/v2\/comments?post=4176"}],"version-history":[{"count":1,"href":"https:\/\/staging.wilegal.it\/en\/wp-json\/wp\/v2\/posts\/4176\/revisions"}],"predecessor-version":[{"id":4178,"href":"https:\/\/staging.wilegal.it\/en\/wp-json\/wp\/v2\/posts\/4176\/revisions\/4178"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.wilegal.it\/en\/wp-json\/wp\/v2\/media\/4075"}],"wp:attachment":[{"href":"https:\/\/staging.wilegal.it\/en\/wp-json\/wp\/v2\/media?parent=4176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.wilegal.it\/en\/wp-json\/wp\/v2\/categories?post=4176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.wilegal.it\/en\/wp-json\/wp\/v2\/tags?post=4176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}