{"id":4180,"date":"2021-07-06T09:56:00","date_gmt":"2021-07-06T09:56:00","guid":{"rendered":"https:\/\/staging.wilegal.it\/?p=4180"},"modified":"2022-09-09T10:13:14","modified_gmt":"2022-09-09T10:13:14","slug":"wi-legal-avvocati-del-lavoro-e-lo-studio-che-ha-fatto-segnare-il-record-di-crescita-nel-2020-72","status":"publish","type":"post","link":"https:\/\/staging.wilegal.it\/en\/wi-legal-avvocati-del-lavoro-e-lo-studio-che-ha-fatto-segnare-il-record-di-crescita-nel-2020-72\/","title":{"rendered":"WI LEGAL| Avvocati del lavoro, \u00e8 lo studio che ha fatto segnare il record di crescita nel 2020: +72%."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">In un&#8217;interessante intervista a MAG, Gianluca Spolverato racconta WI LEGAL, un progetto professionale incentrato sul lavoro e sulle persone che nell&#8217;ultimo anno si \u00e8 messo in luce per il <strong>record di crescita realizzato nel 2020: +72%.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cIl nostro \u00e8 un progetto di crescita unico in quanto considera il lavoro fattore determinante della crescita delle aziende e delle persone &#8211; ha commentato Gianluca Spolverato &#8211; servono persone che abbiano voglia di contribuire a un progetto comune, in cui si identificano. Prima le persone, poi le competenze: queste&nbsp;ultime sono importanti, ma oggi ci sono molti consulenti e avvocati bravi. Riuscire&nbsp;a mettere insieme grandi professionisti, ottimi avvocati significa coinvolgerli in un progetto che ha un\u2019identit\u00e0 forte, e noi crediamo di avere un progetto con questa caratteristica\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Leggi l&#8217;intervista completa a pag. 68 del numero di MAG di luglio:&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/legalcommunity.it\/wp-content\/uploads\/2021\/07\/Mag165_20210705_LcSrl_LC.pdf\" target=\"_blank\">https:\/\/legalcommunity.it\/wp-content\/uploads\/2021\/07\/Mag165_20210705_LcSrl_LC.pdf<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In un&#8217;interessante intervista a MAG, Gianluca Spolverato racconta WI LEGAL, un progetto professionale incentrato sul lavoro e sulle persone che nell&#8217;ultimo anno si \u00e8 messo in luce per il record di crescita realizzato nel 2020: +72%. \u201cIl nostro \u00e8 un progetto di crescita unico in quanto considera il lavoro fattore determinante della crescita delle aziende [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3936,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32],"tags":[],"class_list":["post-4180","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interviews"],"_links":{"self":[{"href":"https:\/\/staging.wilegal.it\/en\/wp-json\/wp\/v2\/posts\/4180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.wilegal.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.wilegal.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.wilegal.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.wilegal.it\/en\/wp-json\/wp\/v2\/comments?post=4180"}],"version-history":[{"count":2,"href":"https:\/\/staging.wilegal.it\/en\/wp-json\/wp\/v2\/posts\/4180\/revisions"}],"predecessor-version":[{"id":4186,"href":"https:\/\/staging.wilegal.it\/en\/wp-json\/wp\/v2\/posts\/4180\/revisions\/4186"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.wilegal.it\/en\/wp-json\/wp\/v2\/media\/3936"}],"wp:attachment":[{"href":"https:\/\/staging.wilegal.it\/en\/wp-json\/wp\/v2\/media?parent=4180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.wilegal.it\/en\/wp-json\/wp\/v2\/categories?post=4180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.wilegal.it\/en\/wp-json\/wp\/v2\/tags?post=4180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}