{"id":5383,"date":"2024-02-15T08:00:14","date_gmt":"2024-02-15T08:00:14","guid":{"rendered":"https:\/\/staging.wilegal.it\/?p=5383"},"modified":"2024-02-15T08:00:36","modified_gmt":"2024-02-15T08:00:36","slug":"wi-legal-nomina-socia-emiliana-maria-dal-bon","status":"publish","type":"post","link":"https:\/\/staging.wilegal.it\/en\/wi-legal-nomina-socia-emiliana-maria-dal-bon\/","title":{"rendered":"WI LEGAL nomina socia Emiliana Maria Dal Bon"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u201cSono molto contento per la nomina di Emiliana Maria Dal Bon a socia dello Studio. Emiliana ha da sempre contribuito al consolidamento della nostra <strong>sede di Modena<\/strong>\u00a0e del nostro progetto, diventando un punto di riferimento e un supporto importante all\u2019interno della nostra realt\u00e0. Il suo ingresso si inserisce appieno nel nostro\u00a0<strong>percorso di valorizzazione e di crescita,\u00a0<\/strong>in quanto ci ha permesso di incrementare ulteriormentela nostra expertise<strong>\u00a0nella formazione e nella consulenza del lavoro\u201d-\u00a0<\/strong>ha commentato<strong> Gianluca Spolverato,<\/strong>\u00a0Managing Partner di WI LEGAL.<br><br><strong>Emiliana Maria Dal Bon\u00a0<\/strong>ha maturato rilevanti esperienze nell\u2019ambito del contenzioso stragiudiziale, delle relazioni sindacali, della contrattazione individuale e collettiva oltre che nella gestione del lavoro somministrato e del lavoro all\u2019estero. Si occupa, inoltre, di formazione in materia di diritto del lavoro, soprattutto personalizzata.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con la nuova nomina di Emiliana Maria Dal Bon, <strong>i soci dello studio WI LEGAL salgono a 9<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cSono molto contento per la nomina di Emiliana Maria Dal Bon a socia dello Studio. Emiliana ha da sempre contribuito al consolidamento della nostra sede di Modena\u00a0e del nostro progetto, diventando un punto di riferimento e un supporto importante all\u2019interno della nostra realt\u00e0. Il suo ingresso si inserisce appieno nel nostro\u00a0percorso di valorizzazione e di [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3600,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[],"class_list":["post-5383","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-institutional-news"],"_links":{"self":[{"href":"https:\/\/staging.wilegal.it\/en\/wp-json\/wp\/v2\/posts\/5383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.wilegal.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.wilegal.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.wilegal.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.wilegal.it\/en\/wp-json\/wp\/v2\/comments?post=5383"}],"version-history":[{"count":1,"href":"https:\/\/staging.wilegal.it\/en\/wp-json\/wp\/v2\/posts\/5383\/revisions"}],"predecessor-version":[{"id":5385,"href":"https:\/\/staging.wilegal.it\/en\/wp-json\/wp\/v2\/posts\/5383\/revisions\/5385"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.wilegal.it\/en\/wp-json\/wp\/v2\/media\/3600"}],"wp:attachment":[{"href":"https:\/\/staging.wilegal.it\/en\/wp-json\/wp\/v2\/media?parent=5383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.wilegal.it\/en\/wp-json\/wp\/v2\/categories?post=5383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.wilegal.it\/en\/wp-json\/wp\/v2\/tags?post=5383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}